
{"id":2855,"date":"2023-11-06T12:36:13","date_gmt":"2023-11-06T11:36:13","guid":{"rendered":"https:\/\/www.wakonda.eu\/?page_id=2855"},"modified":"2023-11-07T11:26:53","modified_gmt":"2023-11-07T10:26:53","slug":"ambition-es","status":"publish","type":"page","link":"https:\/\/www.wakonda.eu\/es\/ambition-es\/","title":{"rendered":"Ambition"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row full_width=&#8221;stretch_row&#8221; css=&#8221;.vc_custom_1689067673804{background-image: url(https:\/\/www.wakonda.eu\/wp-content\/uploads\/sites\/39\/2023\/07\/Wakonda_img_VISION_Ambition.jpg?id=1985) !important;background-position: center !important;background-repeat: no-repeat !important;background-size: cover !important;}&#8221; el_id=&#8221;riga_intestazione&#8221;][vc_column width=&#8221;1\/2&#8243;][vc_column_text]vision<\/p>\n<h2>AMBICI\u00d3N<\/h2>\n<p>[\/vc_column_text][\/vc_column][vc_column width=&#8221;1\/2&#8243;][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row_content_no_spaces&#8221; equal_height=&#8221;yes&#8221; el_id=&#8221;riga_benefici&#8221;][vc_column width=&#8221;1\/6&#8243; el_class=&#8221;colonna_blu&#8221;][\/vc_column][vc_column width=&#8221;2\/6&#8243; el_class=&#8221;colonna_arancio&#8221;][vc_column_text]Queremos promover el desarrollo sostenible, que sea aplicable tanto a los pa\u00edses de la cuenca mediterr\u00e1nea como a las econom\u00edas en desarrollo de \u00c1frica y Oriente Medio..[\/vc_column_text][\/vc_column][vc_column width=&#8221;3\/6&#8243; el_class=&#8221;colonna_verde&#8221;][\/vc_column][\/vc_row][vc_row equal_height=&#8221;yes&#8221; el_id=&#8221;citazione&#8221;][vc_column el_class=&#8221;colonna_blu&#8221;][vc_empty_space][vc_column_text]<\/p>\n<h2><span id=\"slogan_ambition\">&#8220;Podemos hacer productivas las tierras no utilizadas, produciendo alimentos, forraje y energ\u00eda. A un costo nunca antes visto, y con un desarrollo econ\u00f3mico compatible que mejore el medio ambiente.&#8221;<\/span><\/h2>\n<p style=\"text-align: right;\"><span class=\"nome_citazione\"><strong>Fabrizio Sibilla<\/strong><br \/>\n<\/span>Fundador y Director T\u00e9cnico<\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row equal_height=&#8221;yes&#8221;][vc_column width=&#8221;1\/2&#8243; el_class=&#8221;colonna_blu&#8221;][vc_column_text]<strong>Wakonda ha implementado un sistema de desarrollo que sigue los principios de la econom\u00eda circular, un sistema que hace que las tierras marginales ya no sean utilizables para la producci\u00f3n agr\u00edcola tradicional.<\/strong><\/p>\n<p>Gracias a nuestras metodolog\u00edas es posible alcanzar rendimientos de hasta mil toneladas de producto fresco por hect\u00e1rea al a\u00f1o, con un coste por tonelada baj\u00edsimo. Esto supone una productividad hasta cuatro veces mayor que la del ma\u00edz y utiliza hasta 10 veces menos agua. En zonas semi\u00e1ridas el sistema Wakonda posibilita el desarrollo de la cr\u00eda de animales, tanto para la producci\u00f3n de carne como de leche.[\/vc_column_text][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_column_text]El proceso de transformaci\u00f3n de Ofi nos permite obtener productos alimenticios saludables y de alta calidad, as\u00ed como producir piensos animales ricos en prote\u00ednas aptos para una agricultura sostenible.<\/p>\n<p>Nuestra tecnolog\u00eda nos permite iniciar un sistema de fermentaci\u00f3n exclusivo que nos permite elevar el contenido de prote\u00edna del alimento producido hasta un 30% de la sustancia seca, creando las condiciones para reducir la dependencia de fertilizantes y alimentos for\u00e1neos y satisfacer la demanda cada vez mayor. para la carne y la leche disponibles en el mercado.[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_raw_html]JTNDc2NyaXB0JTIwc3JjJTNEJTIyaHR0cHMlM0ElMkYlMkZhamF4Lmdvb2dsZWFwaXMuY29tJTJGYWpheCUyRmxpYnMlMkZqcXVlcnklMkYzLjYuNCUyRmpxdWVyeS5taW4uanMlMjIlM0UlM0MlMkZzY3JpcHQlM0UlMEElM0NzY3JpcHQlMjB0eXBlJTNEJTIydGV4dCUyRmphdmFzY3JpcHQlMjIlM0UlMEElMEElMEElMjQlMjhkb2N1bWVudCUyOS5yZWFkeSUyOGZ1bmN0aW9uJTI4JTI5JTdCJTBBJTJGJTJGJTIwalF1ZXJ5JTI4ZG9jdW1lbnQlMjkucmVhZHklMjhmdW5jdGlvbiUyOCUyOSU3QiUwQSUwQSUwQSUyMCUyMCUyMCUyMCUyNCUyOCUyMi5pY29uLW5leHQlMjIlMjkuY2xpY2slMjhmdW5jdGlvbiUyOCUyOSU3QiUwQSUyMCUyMCUyMCUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMHZhbG9yZSUyMCUzRCUyMCUyNCUyOCUyMi52Y19jYXJvdXNlbC1zbGlkZWxpbmUtaW5uZXIlMjAlM0UlMjBkaXYlMjIlMjkuaW5kZXglMjglMjQlMjglMjIudmNfY2Fyb3VzZWwtc2xpZGVsaW5lLWlubmVyJTIwJTNFJTIwZGl2LnZjX2FjdGl2ZSUyMiUyOSUyOSUzQiUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMHZhbG9yZV9pbmNyJTIwJTNEJTIwdmFsb3JlJTIwJTJCJTIwMSUzQiUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMHZhciUyMGlkZW50aWYlMjAlM0QlMjAlMjglMjIlMjN0JTIyJTIwJTJCJTIwdmFsb3JlX2luY3IlMjklM0IlMEElMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMkYlMkYlMjBhbGVydCUyMCUyOGlkZW50aWYlMjklM0IlMEElMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMkYlMkYlMjBhbGVydCUyMCUyOHZhbG9yZSUyOSUzQiUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyNCUyOCUyMi5tYWRyZSUyMCUzRSUyMC52Y19jb2x1bW4taW5uZXIlMjAlM0UlMjAud3BiX3dyYXBwZXIlMjIlMjkuY2hpbGRyZW4lMjglMjkuaGlkZSUyOCUyOSUzQiUyMCUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyNCUyOGlkZW50aWYlMjkuc2hvdyUyOCUyOSUzQiUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUwQSUyRiUyRiUyMCUyMGFsZXJ0JTIwJTI4JTIyY2FpbyUyMiUyOSUzQiUwQSUwQSUyMCUyMCU3RCUyOSUzQiUyMCUwQSUwQSUyNCUyOCUyMi5pY29uLXByZXYlMjIlMjkuY2xpY2slMjhmdW5jdGlvbiUyOCUyOSU3QiUwQSUyMCUyMCUyMCUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMHZhbG9yZSUyMCUzRCUyMCUyNCUyOCUyMi52Y19jYXJvdXNlbC1zbGlkZWxpbmUtaW5uZXIlMjAlM0UlMjBkaXYlMjIlMjkuaW5kZXglMjglMjQlMjglMjIudmNfY2Fyb3VzZWwtc2xpZGVsaW5lLWlubmVyJTIwJTNFJTIwZGl2LnZjX2FjdGl2ZSUyMiUyOSUyOSUzQiUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMHZhbG9yZV9pbmNyJTIwJTNEJTIwdmFsb3JlJTIwLTElM0IlMEElMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjB2YXIlMjBpZGVudGlmJTIwJTNEJTIwJTI4JTIyJTIzdCUyMiUyMCUyQiUyMHZhbG9yZV9pbmNyJTI5JTNCJTBBJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTJGJTJGYWxlcnQlMjAlMjhpZGVudGlmJTI5JTNCJTBBJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTJGJTJGJTIwYWxlcnQlMjAlMjh2YWxvcmUlMjklM0IlMEElMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjQlMjglMjIubWFkcmUlMjAlM0UlMjAudmNfY29sdW1uLWlubmVyJTIwJTNFJTIwLndwYl93cmFwcGVyJTIyJTI5LmNoaWxkcmVuJTI4JTI5LmhpZGUlMjglMjklM0IlMEElMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjQlMjhpZGVudGlmJTI5LnNob3clMjglMjklM0IlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMEElMkYlMkYlMjAlMjBhbGVydCUyMCUyOCUyMmNhaW8lMjIlMjklM0IlMEElMEElMjAlMjAlN0QlMjklM0IlMjAlMjAlMEElMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMEElMEElMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMkYlMkZhbGVydCUyMCUyOCUyMkNJQU8lMjIlMjklM0IlMEElMjAlMjAlMjAlMjAlN0QlMjklM0IlMEElMjAlMjAlMjAlMjAlM0MlMkZzY3JpcHQlM0U=[\/vc_raw_html][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; css=&#8221;.vc_custom_1670924541731{background-color: #a67446 !important;}&#8221; el_id=&#8221;agenda_row&#8221;][vc_column][vc_column_text]<\/p>\n<h2>AGENDA 2030<\/h2>\n<p>La Agenda 2030 de Naciones Unidas persigue una lista de 17 objetivos. El sistema Wakonda contribuye al logro de 13 de ellos, con especial atenci\u00f3n a la producci\u00f3n de alimentos, la adaptaci\u00f3n al cambio clim\u00e1tico y la reducci\u00f3n de la pobreza.[\/vc_column_text][vc_row_inner][vc_column_inner][vc_images_carousel images=&#8221;1238,1239,1240,1242,1251,1253,1243,1244,1245,1246,1247,1252,1248&#8243; img_size=&#8221;full&#8221; onclick=&#8221;link_no&#8221; slides_per_view=&#8221;5&#8243; hide_pagination_control=&#8221;yes&#8221; partial_view=&#8221;yes&#8221;][\/vc_column_inner][\/vc_row_inner][vc_row_inner el_id=&#8221;elenco_obiettivi&#8221;][vc_column_inner el_class=&#8221;madre&#8221; width=&#8221;1\/2&#8243;][vc_column_text el_id=&#8221;t0&#8243;]<\/p>\n<h4>Derrotar la probeza<\/h4>\n<p style=\"text-align: justify;\">Tenemos la ambici\u00f3n de poner a disposici\u00f3n un sistema que permita el desarrollo de las zonas \u00e1ridas y semi\u00e1ridas del planeta, posibilitando el cultivo y la ganader\u00eda en zonas donde ahora no es posible, a un precio accesible, con el resultado de aumentar los ingresos. disponibles y reducir la pobreza relativa y absoluta.<\/p>\n<p>[\/vc_column_text][vc_column_text el_id=&#8221;t1&#8243;]<\/p>\n<h4>Derrota el hambre<\/h4>\n<p style=\"text-align: justify;\">Nuestra mayor ambici\u00f3n es alimentar el planeta y ayudar a vencer el hambre, y la Opuntia es perfecta para este objetivo, porque nos permite recuperar tierras menos f\u00e9rtiles y marginales y producir piensos para animales precisamente donde es m\u00e1s dif\u00edcil o imposible criar animales.<\/p>\n<p>[\/vc_column_text][vc_column_text el_id=&#8221;t2&#8243;]<\/p>\n<h4>Salud y Bienestar<\/h4>\n<p>Opuntia consigue regenerar suelos contaminados por metales pesados e hidrocarburos, que muchas veces generan graves problemas por la contaminaci\u00f3n de los acu\u00edferos. Desde Opuntia tambi\u00e9n es posible producir biofloculantes a bajo coste, para la depuraci\u00f3n de aguas residuales y su reutilizaci\u00f3n en el \u00e1mbito agr\u00edcola.[\/vc_column_text][vc_column_text el_id=&#8221;t3&#8243;]<\/p>\n<h4>Igualidad de g\u00e9nero<\/h4>\n<p style=\"text-align: justify;\">El &#8220;trabajo&#8221; es la principal herramienta para el &#8220;empoderamiento&#8221; femenino, para lograr realmente la igualdad de g\u00e9nero. La mayor\u00eda de las actividades de producci\u00f3n y procesamiento de Wakonda pueden ser gestionadas por mujeres, la mecanizaci\u00f3n de la plantaci\u00f3n y el procesamiento les permite trabajar sin necesidad de realizar un gran esfuerzo muscular.<\/p>\n<p>[\/vc_column_text][vc_column_text el_id=&#8221;t4&#8243;]<\/p>\n<h4>Servicios de agua pura y saneamiento<\/h4>\n<p style=\"text-align: justify;\">La gesti\u00f3n eficiente de los recursos h\u00eddricos es un punto distintivo del proyecto Wakonda, gracias al cual se puede obtener el triple de producci\u00f3n de ma\u00edz en una hect\u00e1rea de terreno, consumiendo 10 veces menos agua. El agua ahorrada o extra\u00edda de Ofi puede destinarse a otros usos, mejorando las condiciones de vida y\/o la producci\u00f3n agr\u00edcola.<\/p>\n<p>[\/vc_column_text][vc_column_text el_id=&#8221;t5&#8243;]<\/p>\n<h4>Energia limpia y accesible<\/h4>\n<p style=\"text-align: justify;\">Ofi es la planta ideal para obtener grandes cantidades de biog\u00e1s para cogeneraci\u00f3n el\u00e9ctrica o biometano de forma sostenible: es el cultivo que convive m\u00e1s eficazmente con los campos agrovoltaicos, en particular en terrenos marginales o improductivos para cultivos tradicionales.<\/p>\n<p>[\/vc_column_text][vc_column_text el_id=&#8221;t6&#8243;]<\/p>\n<h4>Trabajo decente y crecimiento economico<\/h4>\n<p style=\"text-align: justify;\">Wakonda es un sistema ideal para el desarrollo de las zonas \u00e1ridas y semi\u00e1ridas del planeta, es decir, las que sufren las consecuencias del cambio clim\u00e1tico. Es posible fomentar un crecimiento econ\u00f3mico generalizado, inclusivo y sostenible, el empleo pleno y productivo, el trabajo digno tanto para mujeres que hombres, en las zonas m\u00e1s deprimidas de la cuenca mediterr\u00e1nea y en el \u00c1frica subsahariana.<\/p>\n<p>[\/vc_column_text][vc_column_text el_id=&#8221;t7&#8243;]<\/p>\n<h4>Negocios, innovacion e infraestructuras<\/h4>\n<p style=\"text-align: justify;\">Wakonda es un modelo reproducible en m\u00faltiples pa\u00edses, en modo plug &amp; play, con un modelo de transferencia de tecnolog\u00eda destinado a fomentar el desarrollo incluso en zonas deprimidas o con bajo impacto humano, generando empleo y crecimiento sostenible en el mediano y largo plazo.<\/p>\n<p>[\/vc_column_text][vc_column_text el_id=&#8221;t8&#8243;]<\/p>\n<h4>Reducir las desigualdades<\/h4>\n<p style=\"text-align: justify;\">El crecimiento econ\u00f3mico que se puede lograr mediante la adopci\u00f3n de Wakonda es un presagio de un aumento del empleo y de una distribuci\u00f3n del ingreso que parte del sector primario, la agricultura, y por lo tanto, por definici\u00f3n, tiende a reducir las desigualdades y las desigualdades en el ingreso.<\/p>\n<p>[\/vc_column_text][vc_column_text el_id=&#8221;t9&#8243;]<\/p>\n<h4>Ciudades y comuninades sostenibles<\/h4>\n<p style=\"text-align: justify;\">Opuntia contribuye a la biorremediaci\u00f3n de terrenos, permite recuperar vastas \u00e1reas abandonadas, garantiza la biodiversidad gracias a su rusticidad y bajo o nulo aporte de agroqu\u00edmicos, previene la inestabilidad hidrogeol\u00f3gica y es una barrera natural contra incendios.<\/p>\n<p>[\/vc_column_text][vc_column_text el_id=&#8221;t10&#8243;]<\/p>\n<h4>Consumo y produccion responsable<\/h4>\n<p style=\"text-align: justify;\">Con el modelo Wakonda aplicado en grandes extensiones de terreno, es posible producir simult\u00e1neamente alimentos saludables, piensos para la cr\u00eda de animales, biometano y digestato s\u00f3lido y l\u00edquido: todo ello en terrenos marginales y con una baja huella h\u00eddrica, por lo tanto en un proceso que es sostenible desde el punto de vista medioambiental.<\/p>\n<p>[\/vc_column_text][vc_column_text el_id=&#8221;t11&#8243;]<\/p>\n<h4>Lucha contra el cambio climatico<\/h4>\n<p style=\"text-align: justify;\">El modelo Wakonda permite producir mejor piensos, alimentos y bioenerg\u00eda en la misma hect\u00e1rea de tierra, proporcionando una herramienta para adaptarse a los efectos locales del cambio clim\u00e1tico.<\/p>\n<p>[\/vc_column_text][vc_column_text el_id=&#8221;t12&#8243;]<\/p>\n<h4>Vida en la tierra<\/h4>\n<p>Wakonda contribui para proteger, restaurar e promover o uso sustent\u00e1vel do ecossistema terrestre, combatendo a desertifica\u00e7\u00e3o, travando a degrada\u00e7\u00e3o da terra e travando a perda de diversidade biol\u00f3gica. Isto pode ser feito com investimentos de m\u00e9dia\/baixa intensidade de capital em compara\u00e7\u00e3o com a\u00e7\u00f5es de longo prazo.[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/2&#8243;][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner width=&#8221;1\/2&#8243; el_id=&#8221;t12&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;1\/2&#8243;][\/vc_column_inner][\/vc_row_inner][vc_row_inner disable_element=&#8221;yes&#8221;][vc_column_inner][vc_images_carousel images=&#8221;1238,1239,1240,1242,1251,1253,1243,1244,1245,1246,1247,1252,1248,1249,1250,1290&#8243; img_size=&#8221;full&#8221; onclick=&#8221;link_no&#8221; slides_per_view=&#8221;5&#8243; hide_pagination_control=&#8221;yes&#8221; partial_view=&#8221;yes&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"[vc_row full_width=&#8221;stretch_row&#8221; css=&#8221;.vc_custom_1689067673804{background-image: url(https:\/\/www.wakonda.eu\/wp-content\/uploads\/sites\/39\/2023\/07\/Wakonda_img_VISION_Ambition.jpg?id=1985) !important;background-position: center !important;background-repeat: no-repeat !important;background-size: cover !important;}&#8221; el_id=&#8221;riga_intestazione&#8221;][vc_column width=&#8221;1\/2&#8243;][vc_column_text]vision AMBICI\u00d3N [\/vc_column_text][\/vc_column][vc_column width=&#8221;1\/2&#8243;][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row_content_no_spaces&#8221; equal_height=&#8221;yes&#8221; el_id=&#8221;riga_benefici&#8221;][vc_column width=&#8221;1\/6&#8243; el_class=&#8221;colonna_blu&#8221;][\/vc_column][vc_column width=&#8221;2\/6&#8243; el_class=&#8221;colonna_arancio&#8221;][vc_column_text]Queremos promover el desarrollo sostenible, que sea aplicable tanto a los pa\u00edses de la cuenca mediterr\u00e1nea como a las econom\u00edas en desarrollo de \u00c1frica y Oriente Medio..[\/vc_column_text][\/vc_column][vc_column width=&#8221;3\/6&#8243; el_class=&#8221;colonna_verde&#8221;][\/vc_column][\/vc_row][vc_row equal_height=&#8221;yes&#8221; el_id=&#8221;citazione&#8221;][vc_column el_class=&#8221;colonna_blu&#8221;][vc_empty_space][vc_column_text] &#8220;Podemos hacer productivas las tierras no utilizadas, produciendo alimentos, forraje y energ\u00eda. A un costo nunca antes visto, y con un desarrollo econ\u00f3mico compatible que mejore el medio ambiente.&#8221; Fabrizio Sibilla Fundador y Director T\u00e9cnico [\/vc_column_text][\/vc_column][\/vc_row][vc_row equal_height=&#8221;yes&#8221;][vc_column width=&#8221;1\/2&#8243; el_class=&#8221;colonna_blu&#8221;][vc_column_text]Wakonda ha implementado un sistema de desarrollo que sigue los principios de la econom\u00eda circular, un sistema que hace que las tierras marginales ya no sean utilizables para la producci\u00f3n agr\u00edcola tradicional. Gracias a nuestras metodolog\u00edas es posible alcanzar rendimientos de hasta mil toneladas de producto fresco por hect\u00e1rea al a\u00f1o, con un coste por tonelada baj\u00edsimo. Esto supone una productividad hasta cuatro veces mayor que la del ma\u00edz y utiliza hasta 10 veces menos agua. En zonas semi\u00e1ridas el sistema Wakonda posibilita el desarrollo de la cr\u00eda de animales, tanto para la producci\u00f3n de carne como de leche.[\/vc_column_text][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_column_text]El proceso de transformaci\u00f3n de Ofi nos permite obtener productos alimenticios saludables y de alta calidad, as\u00ed como producir piensos animales ricos en prote\u00ednas aptos para una agricultura sostenible. Nuestra tecnolog\u00eda nos permite iniciar un sistema de fermentaci\u00f3n exclusivo que nos permite elevar el contenido de prote\u00edna del alimento producido hasta un 30% de la sustancia seca, creando las condiciones para reducir la dependencia de fertilizantes y alimentos for\u00e1neos y satisfacer la demanda cada vez mayor. para la carne y la leche disponibles en el mercado.[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_raw_html]JTNDc2NyaXB0JTIwc3JjJTNEJTIyaHR0cHMlM0ElMkYlMkZhamF4Lmdvb2dsZWFwaXMuY29tJTJGYWpheCUyRmxpYnMlMkZqcXVlcnklMkYzLjYuNCUyRmpxdWVyeS5taW4uanMlMjIlM0UlM0MlMkZzY3JpcHQlM0UlMEElM0NzY3JpcHQlMjB0eXBlJTNEJTIydGV4dCUyRmphdmFzY3JpcHQlMjIlM0UlMEElMEElMEElMjQlMjhkb2N1bWVudCUyOS5yZWFkeSUyOGZ1bmN0aW9uJTI4JTI5JTdCJTBBJTJGJTJGJTIwalF1ZXJ5JTI4ZG9jdW1lbnQlMjkucmVhZHklMjhmdW5jdGlvbiUyOCUyOSU3QiUwQSUwQSUwQSUyMCUyMCUyMCUyMCUyNCUyOCUyMi5pY29uLW5leHQlMjIlMjkuY2xpY2slMjhmdW5jdGlvbiUyOCUyOSU3QiUwQSUyMCUyMCUyMCUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMHZhbG9yZSUyMCUzRCUyMCUyNCUyOCUyMi52Y19jYXJvdXNlbC1zbGlkZWxpbmUtaW5uZXIlMjAlM0UlMjBkaXYlMjIlMjkuaW5kZXglMjglMjQlMjglMjIudmNfY2Fyb3VzZWwtc2xpZGVsaW5lLWlubmVyJTIwJTNFJTIwZGl2LnZjX2FjdGl2ZSUyMiUyOSUyOSUzQiUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMHZhbG9yZV9pbmNyJTIwJTNEJTIwdmFsb3JlJTIwJTJCJTIwMSUzQiUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMHZhciUyMGlkZW50aWYlMjAlM0QlMjAlMjglMjIlMjN0JTIyJTIwJTJCJTIwdmFsb3JlX2luY3IlMjklM0IlMEElMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMkYlMkYlMjBhbGVydCUyMCUyOGlkZW50aWYlMjklM0IlMEElMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMkYlMkYlMjBhbGVydCUyMCUyOHZhbG9yZSUyOSUzQiUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyNCUyOCUyMi5tYWRyZSUyMCUzRSUyMC52Y19jb2x1bW4taW5uZXIlMjAlM0UlMjAud3BiX3dyYXBwZXIlMjIlMjkuY2hpbGRyZW4lMjglMjkuaGlkZSUyOCUyOSUzQiUyMCUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyNCUyOGlkZW50aWYlMjkuc2hvdyUyOCUyOSUzQiUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUwQSUyRiUyRiUyMCUyMGFsZXJ0JTIwJTI4JTIyY2FpbyUyMiUyOSUzQiUwQSUwQSUyMCUyMCU3RCUyOSUzQiUyMCUwQSUwQSUyNCUyOCUyMi5pY29uLXByZXYlMjIlMjkuY2xpY2slMjhmdW5jdGlvbiUyOCUyOSU3QiUwQSUyMCUyMCUyMCUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMHZhbG9yZSUyMCUzRCUyMCUyNCUyOCUyMi52Y19jYXJvdXNlbC1zbGlkZWxpbmUtaW5uZXIlMjAlM0UlMjBkaXYlMjIlMjkuaW5kZXglMjglMjQlMjglMjIudmNfY2Fyb3VzZWwtc2xpZGVsaW5lLWlubmVyJTIwJTNFJTIwZGl2LnZjX2FjdGl2ZSUyMiUyOSUyOSUzQiUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMHZhbG9yZV9pbmNyJTIwJTNEJTIwdmFsb3JlJTIwLTElM0IlMEElMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjB2YXIlMjBpZGVudGlmJTIwJTNEJTIwJTI4JTIyJTIzdCUyMiUyMCUyQiUyMHZhbG9yZV9pbmNyJTI5JTNCJTBBJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTJGJTJGYWxlcnQlMjAlMjhpZGVudGlmJTI5JTNCJTBBJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTJGJTJGJTIwYWxlcnQlMjAlMjh2YWxvcmUlMjklM0IlMEElMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjQlMjglMjIubWFkcmUlMjAlM0UlMjAudmNfY29sdW1uLWlubmVyJTIwJTNFJTIwLndwYl93cmFwcGVyJTIyJTI5LmNoaWxkcmVuJTI4JTI5LmhpZGUlMjglMjklM0IlMEElMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjQlMjhpZGVudGlmJTI5LnNob3clMjglMjklM0IlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMEElMkYlMkYlMjAlMjBhbGVydCUyMCUyOCUyMmNhaW8lMjIlMjklM0IlMEElMEElMjAlMjAlN0QlMjklM0IlMjAlMjAlMEElMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMEElMEElMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMkYlMkZhbGVydCUyMCUyOCUyMkNJQU8lMjIlMjklM0IlMEElMjAlMjAlMjAlMjAlN0QlMjklM0IlMEElMjAlMjAlMjAlMjAlM0MlMkZzY3JpcHQlM0U=[\/vc_raw_html][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; css=&#8221;.vc_custom_1670924541731{background-color: #a67446 !important;}&#8221; el_id=&#8221;agenda_row&#8221;][vc_column][vc_column_text] AGENDA 2030 La Agenda 2030 de Naciones Unidas persigue una lista de 17 objetivos. El sistema Wakonda contribuye al logro de 13 de ellos, con especial atenci\u00f3n a la producci\u00f3n de alimentos, la adaptaci\u00f3n al cambio clim\u00e1tico y la reducci\u00f3n de la pobreza.[\/vc_column_text][vc_row_inner][vc_column_inner][vc_images_carousel images=&#8221;1238,1239,1240,1242,1251,1253,1243,1244,1245,1246,1247,1252,1248&#8243; img_size=&#8221;full&#8221; onclick=&#8221;link_no&#8221; slides_per_view=&#8221;5&#8243; hide_pagination_control=&#8221;yes&#8221; partial_view=&#8221;yes&#8221;][\/vc_column_inner][\/vc_row_inner][vc_row_inner el_id=&#8221;elenco_obiettivi&#8221;][vc_column_inner el_class=&#8221;madre&#8221; width=&#8221;1\/2&#8243;][vc_column_text el_id=&#8221;t0&#8243;] Derrotar la probeza Tenemos la ambici\u00f3n de poner a disposici\u00f3n un sistema que permita el desarrollo de las zonas \u00e1ridas y semi\u00e1ridas del planeta, posibilitando el cultivo y la ganader\u00eda en zonas donde ahora no es posible, a un precio accesible, con el resultado de aumentar los ingresos. disponibles y reducir la pobreza relativa y absoluta. [\/vc_column_text][vc_column_text el_id=&#8221;t1&#8243;] Derrota el hambre Nuestra mayor ambici\u00f3n es alimentar el planeta y ayudar a vencer el hambre, y la Opuntia es perfecta para este objetivo, porque nos permite recuperar tierras menos f\u00e9rtiles y marginales y producir piensos para animales precisamente donde es m\u00e1s dif\u00edcil o imposible criar animales. [\/vc_column_text][vc_column_text el_id=&#8221;t2&#8243;] Salud y Bienestar Opuntia consigue regenerar suelos contaminados por metales pesados e hidrocarburos, que muchas veces generan graves problemas por la contaminaci\u00f3n de los acu\u00edferos. Desde Opuntia tambi\u00e9n es posible producir biofloculantes a bajo coste, para la depuraci\u00f3n de aguas residuales y su reutilizaci\u00f3n en el \u00e1mbito agr\u00edcola.[\/vc_column_text][vc_column_text el_id=&#8221;t3&#8243;] Igualidad de g\u00e9nero El &#8220;trabajo&#8221; es la principal herramienta para el &#8220;empoderamiento&#8221; femenino, para lograr realmente la igualdad de g\u00e9nero. La mayor\u00eda de las actividades de producci\u00f3n y procesamiento de Wakonda pueden ser gestionadas por mujeres, la mecanizaci\u00f3n de la plantaci\u00f3n y el procesamiento les permite trabajar sin necesidad de realizar un gran esfuerzo muscular. [\/vc_column_text][vc_column_text el_id=&#8221;t4&#8243;] Servicios de agua pura y saneamiento La gesti\u00f3n eficiente de los recursos h\u00eddricos es un punto distintivo del proyecto Wakonda, gracias al cual se puede obtener el triple de producci\u00f3n de ma\u00edz en una hect\u00e1rea de terreno, consumiendo 10 veces menos agua. El agua ahorrada o extra\u00edda de Ofi puede destinarse a otros usos, mejorando las condiciones de vida y\/o la producci\u00f3n agr\u00edcola. [\/vc_column_text][vc_column_text el_id=&#8221;t5&#8243;] Energia limpia y accesible Ofi es la planta ideal para obtener grandes cantidades de biog\u00e1s para cogeneraci\u00f3n el\u00e9ctrica o biometano de forma sostenible: es el cultivo que convive m\u00e1s eficazmente con los campos agrovoltaicos, en particular en terrenos marginales o improductivos para cultivos tradicionales. [\/vc_column_text][vc_column_text el_id=&#8221;t6&#8243;] Trabajo decente y crecimiento economico Wakonda es un sistema ideal para el desarrollo de las zonas \u00e1ridas y semi\u00e1ridas del planeta, es decir, las que sufren las consecuencias del cambio clim\u00e1tico. Es posible fomentar un crecimiento econ\u00f3mico generalizado, inclusivo y sostenible, el empleo pleno y productivo, el trabajo digno tanto para mujeres que hombres, en las zonas m\u00e1s deprimidas de la cuenca mediterr\u00e1nea y en el \u00c1frica subsahariana. [\/vc_column_text][vc_column_text el_id=&#8221;t7&#8243;] Negocios, innovacion e infraestructuras Wakonda es un modelo reproducible en m\u00faltiples pa\u00edses, en modo plug &amp; play, con un modelo de transferencia de tecnolog\u00eda destinado a fomentar el desarrollo incluso en zonas deprimidas o con bajo impacto humano, generando empleo y crecimiento sostenible en el mediano y largo plazo. [\/vc_column_text][vc_column_text el_id=&#8221;t8&#8243;] Reducir las desigualdades El crecimiento econ\u00f3mico que se puede lograr mediante la adopci\u00f3n de Wakonda es un presagio de un aumento del empleo y de una distribuci\u00f3n del ingreso que parte del sector primario, la agricultura, y por lo tanto, por definici\u00f3n, tiende a reducir las desigualdades y las desigualdades en el ingreso. [\/vc_column_text][vc_column_text el_id=&#8221;t9&#8243;] Ciudades y comuninades sostenibles Opuntia contribuye a la biorremediaci\u00f3n de terrenos, permite recuperar vastas \u00e1reas abandonadas, garantiza la biodiversidad gracias a su rusticidad y bajo o nulo aporte de agroqu\u00edmicos, previene la inestabilidad hidrogeol\u00f3gica y es una barrera natural contra incendios. [\/vc_column_text][vc_column_text el_id=&#8221;t10&#8243;] Consumo y produccion responsable Con el modelo Wakonda aplicado en grandes extensiones de terreno, es posible producir simult\u00e1neamente alimentos saludables, piensos para la cr\u00eda de animales, biometano y digestato s\u00f3lido y l\u00edquido: todo ello en terrenos marginales y con una baja huella h\u00eddrica, por lo tanto en un proceso que es sostenible desde el punto de vista medioambiental. [\/vc_column_text][vc_column_text el_id=&#8221;t11&#8243;] Lucha contra el cambio climatico El modelo Wakonda permite producir mejor piensos, alimentos y bioenerg\u00eda en la misma hect\u00e1rea de tierra, proporcionando una herramienta para adaptarse a los efectos locales del cambio clim\u00e1tico. [\/vc_column_text][vc_column_text el_id=&#8221;t12&#8243;] Vida en la tierra Wakonda contribui para proteger, restaurar e promover o uso sustent\u00e1vel do ecossistema terrestre, combatendo a desertifica\u00e7\u00e3o, travando a degrada\u00e7\u00e3o da terra e travando a perda de diversidade biol\u00f3gica. Isto pode ser feito com investimentos de m\u00e9dia\/baixa intensidade de capital em compara\u00e7\u00e3o com a\u00e7\u00f5es de longo prazo.[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/2&#8243;][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner width=&#8221;1\/2&#8243; el_id=&#8221;t12&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;1\/2&#8243;][\/vc_column_inner][\/vc_row_inner][vc_row_inner disable_element=&#8221;yes&#8221;][vc_column_inner][vc_images_carousel images=&#8221;1238,1239,1240,1242,1251,1253,1243,1244,1245,1246,1247,1252,1248,1249,1250,1290&#8243; img_size=&#8221;full&#8221; onclick=&#8221;link_no&#8221; slides_per_view=&#8221;5&#8243; hide_pagination_control=&#8221;yes&#8221; partial_view=&#8221;yes&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row]","protected":false},"author":25,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"site-sidebar-layout":"no-sidebar","site-content-layout":"plain-container","ast-site-content-layout":"normal-width-container","site-content-style":"unboxed","site-sidebar-style":"unboxed","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"default","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-2855","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ambition - Wakonda<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.wakonda.eu\/es\/ambition-es\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ambition - Wakonda\" \/>\n<meta property=\"og:description\" content=\"[vc_row full_width=&#8221;stretch_row&#8221; css=&#8221;.vc_custom_1689067673804{background-image: url(https:\/\/www.wakonda.eu\/wp-content\/uploads\/sites\/39\/2023\/07\/Wakonda_img_VISION_Ambition.jpg?id=1985) !important;background-position: center !important;background-repeat: no-repeat !important;background-size: cover !important;}&#8221; el_id=&#8221;riga_intestazione&#8221;][vc_column width=&#8221;1\/2&#8243;][vc_column_text]vision AMBICI\u00d3N [\/vc_column_text][\/vc_column][vc_column width=&#8221;1\/2&#8243;][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row_content_no_spaces&#8221; equal_height=&#8221;yes&#8221; el_id=&#8221;riga_benefici&#8221;][vc_column width=&#8221;1\/6&#8243; el_class=&#8221;colonna_blu&#8221;][\/vc_column][vc_column width=&#8221;2\/6&#8243; el_class=&#8221;colonna_arancio&#8221;][vc_column_text]Queremos promover el desarrollo sostenible, que sea aplicable tanto a los pa\u00edses de la cuenca mediterr\u00e1nea como a las econom\u00edas en desarrollo de \u00c1frica y Oriente Medio..[\/vc_column_text][\/vc_column][vc_column width=&#8221;3\/6&#8243; el_class=&#8221;colonna_verde&#8221;][\/vc_column][\/vc_row][vc_row equal_height=&#8221;yes&#8221; el_id=&#8221;citazione&#8221;][vc_column el_class=&#8221;colonna_blu&#8221;][vc_empty_space][vc_column_text] &#8220;Podemos hacer productivas las tierras no utilizadas, produciendo alimentos, forraje y energ\u00eda. A un costo nunca antes visto, y con un desarrollo econ\u00f3mico compatible que mejore el medio ambiente.&#8221; Fabrizio Sibilla Fundador y Director T\u00e9cnico [\/vc_column_text][\/vc_column][\/vc_row][vc_row equal_height=&#8221;yes&#8221;][vc_column width=&#8221;1\/2&#8243; el_class=&#8221;colonna_blu&#8221;][vc_column_text]Wakonda ha implementado un sistema de desarrollo que sigue los principios de la econom\u00eda circular, un sistema que hace que las tierras marginales ya no sean utilizables para la producci\u00f3n agr\u00edcola tradicional. Gracias a nuestras metodolog\u00edas es posible alcanzar rendimientos de hasta mil toneladas de producto fresco por hect\u00e1rea al a\u00f1o, con un coste por tonelada baj\u00edsimo. Esto supone una productividad hasta cuatro veces mayor que la del ma\u00edz y utiliza hasta 10 veces menos agua. En zonas semi\u00e1ridas el sistema Wakonda posibilita el desarrollo de la cr\u00eda de animales, tanto para la producci\u00f3n de carne como de leche.[\/vc_column_text][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_column_text]El proceso de transformaci\u00f3n de Ofi nos permite obtener productos alimenticios saludables y de alta calidad, as\u00ed como producir piensos animales ricos en prote\u00ednas aptos para una agricultura sostenible. Nuestra tecnolog\u00eda nos permite iniciar un sistema de fermentaci\u00f3n exclusivo que nos permite elevar el contenido de prote\u00edna del alimento producido hasta un 30% de la sustancia seca, creando las condiciones para reducir la dependencia de fertilizantes y alimentos for\u00e1neos y satisfacer la demanda cada vez mayor. para la carne y la leche disponibles en el mercado.[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_raw_html]JTNDc2NyaXB0JTIwc3JjJTNEJTIyaHR0cHMlM0ElMkYlMkZhamF4Lmdvb2dsZWFwaXMuY29tJTJGYWpheCUyRmxpYnMlMkZqcXVlcnklMkYzLjYuNCUyRmpxdWVyeS5taW4uanMlMjIlM0UlM0MlMkZzY3JpcHQlM0UlMEElM0NzY3JpcHQlMjB0eXBlJTNEJTIydGV4dCUyRmphdmFzY3JpcHQlMjIlM0UlMEElMEElMEElMjQlMjhkb2N1bWVudCUyOS5yZWFkeSUyOGZ1bmN0aW9uJTI4JTI5JTdCJTBBJTJGJTJGJTIwalF1ZXJ5JTI4ZG9jdW1lbnQlMjkucmVhZHklMjhmdW5jdGlvbiUyOCUyOSU3QiUwQSUwQSUwQSUyMCUyMCUyMCUyMCUyNCUyOCUyMi5pY29uLW5leHQlMjIlMjkuY2xpY2slMjhmdW5jdGlvbiUyOCUyOSU3QiUwQSUyMCUyMCUyMCUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMHZhbG9yZSUyMCUzRCUyMCUyNCUyOCUyMi52Y19jYXJvdXNlbC1zbGlkZWxpbmUtaW5uZXIlMjAlM0UlMjBkaXYlMjIlMjkuaW5kZXglMjglMjQlMjglMjIudmNfY2Fyb3VzZWwtc2xpZGVsaW5lLWlubmVyJTIwJTNFJTIwZGl2LnZjX2FjdGl2ZSUyMiUyOSUyOSUzQiUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMHZhbG9yZV9pbmNyJTIwJTNEJTIwdmFsb3JlJTIwJTJCJTIwMSUzQiUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMHZhciUyMGlkZW50aWYlMjAlM0QlMjAlMjglMjIlMjN0JTIyJTIwJTJCJTIwdmFsb3JlX2luY3IlMjklM0IlMEElMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMkYlMkYlMjBhbGVydCUyMCUyOGlkZW50aWYlMjklM0IlMEElMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMkYlMkYlMjBhbGVydCUyMCUyOHZhbG9yZSUyOSUzQiUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyNCUyOCUyMi5tYWRyZSUyMCUzRSUyMC52Y19jb2x1bW4taW5uZXIlMjAlM0UlMjAud3BiX3dyYXBwZXIlMjIlMjkuY2hpbGRyZW4lMjglMjkuaGlkZSUyOCUyOSUzQiUyMCUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyNCUyOGlkZW50aWYlMjkuc2hvdyUyOCUyOSUzQiUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUwQSUyRiUyRiUyMCUyMGFsZXJ0JTIwJTI4JTIyY2FpbyUyMiUyOSUzQiUwQSUwQSUyMCUyMCU3RCUyOSUzQiUyMCUwQSUwQSUyNCUyOCUyMi5pY29uLXByZXYlMjIlMjkuY2xpY2slMjhmdW5jdGlvbiUyOCUyOSU3QiUwQSUyMCUyMCUyMCUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMHZhbG9yZSUyMCUzRCUyMCUyNCUyOCUyMi52Y19jYXJvdXNlbC1zbGlkZWxpbmUtaW5uZXIlMjAlM0UlMjBkaXYlMjIlMjkuaW5kZXglMjglMjQlMjglMjIudmNfY2Fyb3VzZWwtc2xpZGVsaW5lLWlubmVyJTIwJTNFJTIwZGl2LnZjX2FjdGl2ZSUyMiUyOSUyOSUzQiUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMHZhbG9yZV9pbmNyJTIwJTNEJTIwdmFsb3JlJTIwLTElM0IlMEElMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjB2YXIlMjBpZGVudGlmJTIwJTNEJTIwJTI4JTIyJTIzdCUyMiUyMCUyQiUyMHZhbG9yZV9pbmNyJTI5JTNCJTBBJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTJGJTJGYWxlcnQlMjAlMjhpZGVudGlmJTI5JTNCJTBBJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTJGJTJGJTIwYWxlcnQlMjAlMjh2YWxvcmUlMjklM0IlMEElMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjQlMjglMjIubWFkcmUlMjAlM0UlMjAudmNfY29sdW1uLWlubmVyJTIwJTNFJTIwLndwYl93cmFwcGVyJTIyJTI5LmNoaWxkcmVuJTI4JTI5LmhpZGUlMjglMjklM0IlMEElMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjQlMjhpZGVudGlmJTI5LnNob3clMjglMjklM0IlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMEElMkYlMkYlMjAlMjBhbGVydCUyMCUyOCUyMmNhaW8lMjIlMjklM0IlMEElMEElMjAlMjAlN0QlMjklM0IlMjAlMjAlMEElMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMEElMEElMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMkYlMkZhbGVydCUyMCUyOCUyMkNJQU8lMjIlMjklM0IlMEElMjAlMjAlMjAlMjAlN0QlMjklM0IlMEElMjAlMjAlMjAlMjAlM0MlMkZzY3JpcHQlM0U=[\/vc_raw_html][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; css=&#8221;.vc_custom_1670924541731{background-color: #a67446 !important;}&#8221; el_id=&#8221;agenda_row&#8221;][vc_column][vc_column_text] AGENDA 2030 La Agenda 2030 de Naciones Unidas persigue una lista de 17 objetivos. El sistema Wakonda contribuye al logro de 13 de ellos, con especial atenci\u00f3n a la producci\u00f3n de alimentos, la adaptaci\u00f3n al cambio clim\u00e1tico y la reducci\u00f3n de la pobreza.[\/vc_column_text][vc_row_inner][vc_column_inner][vc_images_carousel images=&#8221;1238,1239,1240,1242,1251,1253,1243,1244,1245,1246,1247,1252,1248&#8243; img_size=&#8221;full&#8221; onclick=&#8221;link_no&#8221; slides_per_view=&#8221;5&#8243; hide_pagination_control=&#8221;yes&#8221; partial_view=&#8221;yes&#8221;][\/vc_column_inner][\/vc_row_inner][vc_row_inner el_id=&#8221;elenco_obiettivi&#8221;][vc_column_inner el_class=&#8221;madre&#8221; width=&#8221;1\/2&#8243;][vc_column_text el_id=&#8221;t0&#8243;] Derrotar la probeza Tenemos la ambici\u00f3n de poner a disposici\u00f3n un sistema que permita el desarrollo de las zonas \u00e1ridas y semi\u00e1ridas del planeta, posibilitando el cultivo y la ganader\u00eda en zonas donde ahora no es posible, a un precio accesible, con el resultado de aumentar los ingresos. disponibles y reducir la pobreza relativa y absoluta. [\/vc_column_text][vc_column_text el_id=&#8221;t1&#8243;] Derrota el hambre Nuestra mayor ambici\u00f3n es alimentar el planeta y ayudar a vencer el hambre, y la Opuntia es perfecta para este objetivo, porque nos permite recuperar tierras menos f\u00e9rtiles y marginales y producir piensos para animales precisamente donde es m\u00e1s dif\u00edcil o imposible criar animales. [\/vc_column_text][vc_column_text el_id=&#8221;t2&#8243;] Salud y Bienestar Opuntia consigue regenerar suelos contaminados por metales pesados e hidrocarburos, que muchas veces generan graves problemas por la contaminaci\u00f3n de los acu\u00edferos. Desde Opuntia tambi\u00e9n es posible producir biofloculantes a bajo coste, para la depuraci\u00f3n de aguas residuales y su reutilizaci\u00f3n en el \u00e1mbito agr\u00edcola.[\/vc_column_text][vc_column_text el_id=&#8221;t3&#8243;] Igualidad de g\u00e9nero El &#8220;trabajo&#8221; es la principal herramienta para el &#8220;empoderamiento&#8221; femenino, para lograr realmente la igualdad de g\u00e9nero. La mayor\u00eda de las actividades de producci\u00f3n y procesamiento de Wakonda pueden ser gestionadas por mujeres, la mecanizaci\u00f3n de la plantaci\u00f3n y el procesamiento les permite trabajar sin necesidad de realizar un gran esfuerzo muscular. [\/vc_column_text][vc_column_text el_id=&#8221;t4&#8243;] Servicios de agua pura y saneamiento La gesti\u00f3n eficiente de los recursos h\u00eddricos es un punto distintivo del proyecto Wakonda, gracias al cual se puede obtener el triple de producci\u00f3n de ma\u00edz en una hect\u00e1rea de terreno, consumiendo 10 veces menos agua. El agua ahorrada o extra\u00edda de Ofi puede destinarse a otros usos, mejorando las condiciones de vida y\/o la producci\u00f3n agr\u00edcola. [\/vc_column_text][vc_column_text el_id=&#8221;t5&#8243;] Energia limpia y accesible Ofi es la planta ideal para obtener grandes cantidades de biog\u00e1s para cogeneraci\u00f3n el\u00e9ctrica o biometano de forma sostenible: es el cultivo que convive m\u00e1s eficazmente con los campos agrovoltaicos, en particular en terrenos marginales o improductivos para cultivos tradicionales. [\/vc_column_text][vc_column_text el_id=&#8221;t6&#8243;] Trabajo decente y crecimiento economico Wakonda es un sistema ideal para el desarrollo de las zonas \u00e1ridas y semi\u00e1ridas del planeta, es decir, las que sufren las consecuencias del cambio clim\u00e1tico. Es posible fomentar un crecimiento econ\u00f3mico generalizado, inclusivo y sostenible, el empleo pleno y productivo, el trabajo digno tanto para mujeres que hombres, en las zonas m\u00e1s deprimidas de la cuenca mediterr\u00e1nea y en el \u00c1frica subsahariana. [\/vc_column_text][vc_column_text el_id=&#8221;t7&#8243;] Negocios, innovacion e infraestructuras Wakonda es un modelo reproducible en m\u00faltiples pa\u00edses, en modo plug &amp; play, con un modelo de transferencia de tecnolog\u00eda destinado a fomentar el desarrollo incluso en zonas deprimidas o con bajo impacto humano, generando empleo y crecimiento sostenible en el mediano y largo plazo. [\/vc_column_text][vc_column_text el_id=&#8221;t8&#8243;] Reducir las desigualdades El crecimiento econ\u00f3mico que se puede lograr mediante la adopci\u00f3n de Wakonda es un presagio de un aumento del empleo y de una distribuci\u00f3n del ingreso que parte del sector primario, la agricultura, y por lo tanto, por definici\u00f3n, tiende a reducir las desigualdades y las desigualdades en el ingreso. [\/vc_column_text][vc_column_text el_id=&#8221;t9&#8243;] Ciudades y comuninades sostenibles Opuntia contribuye a la biorremediaci\u00f3n de terrenos, permite recuperar vastas \u00e1reas abandonadas, garantiza la biodiversidad gracias a su rusticidad y bajo o nulo aporte de agroqu\u00edmicos, previene la inestabilidad hidrogeol\u00f3gica y es una barrera natural contra incendios. [\/vc_column_text][vc_column_text el_id=&#8221;t10&#8243;] Consumo y produccion responsable Con el modelo Wakonda aplicado en grandes extensiones de terreno, es posible producir simult\u00e1neamente alimentos saludables, piensos para la cr\u00eda de animales, biometano y digestato s\u00f3lido y l\u00edquido: todo ello en terrenos marginales y con una baja huella h\u00eddrica, por lo tanto en un proceso que es sostenible desde el punto de vista medioambiental. [\/vc_column_text][vc_column_text el_id=&#8221;t11&#8243;] Lucha contra el cambio climatico El modelo Wakonda permite producir mejor piensos, alimentos y bioenerg\u00eda en la misma hect\u00e1rea de tierra, proporcionando una herramienta para adaptarse a los efectos locales del cambio clim\u00e1tico. [\/vc_column_text][vc_column_text el_id=&#8221;t12&#8243;] Vida en la tierra Wakonda contribui para proteger, restaurar e promover o uso sustent\u00e1vel do ecossistema terrestre, combatendo a desertifica\u00e7\u00e3o, travando a degrada\u00e7\u00e3o da terra e travando a perda de diversidade biol\u00f3gica. Isto pode ser feito com investimentos de m\u00e9dia\/baixa intensidade de capital em compara\u00e7\u00e3o com a\u00e7\u00f5es de longo prazo.[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/2&#8243;][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner width=&#8221;1\/2&#8243; el_id=&#8221;t12&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;1\/2&#8243;][\/vc_column_inner][\/vc_row_inner][vc_row_inner disable_element=&#8221;yes&#8221;][vc_column_inner][vc_images_carousel images=&#8221;1238,1239,1240,1242,1251,1253,1243,1244,1245,1246,1247,1252,1248,1249,1250,1290&#8243; img_size=&#8221;full&#8221; onclick=&#8221;link_no&#8221; slides_per_view=&#8221;5&#8243; hide_pagination_control=&#8221;yes&#8221; partial_view=&#8221;yes&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.wakonda.eu\/es\/ambition-es\/\" \/>\n<meta property=\"og:site_name\" content=\"Wakonda\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-07T10:26:53+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.wakonda.eu\\\/es\\\/ambition-es\\\/\",\"url\":\"https:\\\/\\\/www.wakonda.eu\\\/es\\\/ambition-es\\\/\",\"name\":\"Ambition - Wakonda\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.wakonda.eu\\\/#website\"},\"datePublished\":\"2023-11-06T11:36:13+00:00\",\"dateModified\":\"2023-11-07T10:26:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.wakonda.eu\\\/es\\\/ambition-es\\\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.wakonda.eu\\\/es\\\/ambition-es\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.wakonda.eu\\\/es\\\/ambition-es\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.wakonda.eu\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ambition\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.wakonda.eu\\\/#website\",\"url\":\"https:\\\/\\\/www.wakonda.eu\\\/\",\"name\":\"Wakonda\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.wakonda.eu\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.wakonda.eu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.wakonda.eu\\\/#organization\",\"name\":\"Wakonda\",\"url\":\"https:\\\/\\\/www.wakonda.eu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/www.wakonda.eu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.wakonda.eu\\\/wp-content\\\/uploads\\\/sites\\\/39\\\/2023\\\/05\\\/cropped-logo_wakonda.png\",\"contentUrl\":\"https:\\\/\\\/www.wakonda.eu\\\/wp-content\\\/uploads\\\/sites\\\/39\\\/2023\\\/05\\\/cropped-logo_wakonda.png\",\"width\":256,\"height\":57,\"caption\":\"Wakonda\"},\"image\":{\"@id\":\"https:\\\/\\\/www.wakonda.eu\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ambition - Wakonda","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.wakonda.eu\/es\/ambition-es\/","og_locale":"es_ES","og_type":"article","og_title":"Ambition - Wakonda","og_description":"[vc_row full_width=&#8221;stretch_row&#8221; css=&#8221;.vc_custom_1689067673804{background-image: url(https:\/\/www.wakonda.eu\/wp-content\/uploads\/sites\/39\/2023\/07\/Wakonda_img_VISION_Ambition.jpg?id=1985) !important;background-position: center !important;background-repeat: no-repeat !important;background-size: cover !important;}&#8221; el_id=&#8221;riga_intestazione&#8221;][vc_column width=&#8221;1\/2&#8243;][vc_column_text]vision AMBICI\u00d3N [\/vc_column_text][\/vc_column][vc_column width=&#8221;1\/2&#8243;][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row_content_no_spaces&#8221; equal_height=&#8221;yes&#8221; el_id=&#8221;riga_benefici&#8221;][vc_column width=&#8221;1\/6&#8243; el_class=&#8221;colonna_blu&#8221;][\/vc_column][vc_column width=&#8221;2\/6&#8243; el_class=&#8221;colonna_arancio&#8221;][vc_column_text]Queremos promover el desarrollo sostenible, que sea aplicable tanto a los pa\u00edses de la cuenca mediterr\u00e1nea como a las econom\u00edas en desarrollo de \u00c1frica y Oriente Medio..[\/vc_column_text][\/vc_column][vc_column width=&#8221;3\/6&#8243; el_class=&#8221;colonna_verde&#8221;][\/vc_column][\/vc_row][vc_row equal_height=&#8221;yes&#8221; el_id=&#8221;citazione&#8221;][vc_column el_class=&#8221;colonna_blu&#8221;][vc_empty_space][vc_column_text] &#8220;Podemos hacer productivas las tierras no utilizadas, produciendo alimentos, forraje y energ\u00eda. A un costo nunca antes visto, y con un desarrollo econ\u00f3mico compatible que mejore el medio ambiente.&#8221; Fabrizio Sibilla Fundador y Director T\u00e9cnico [\/vc_column_text][\/vc_column][\/vc_row][vc_row equal_height=&#8221;yes&#8221;][vc_column width=&#8221;1\/2&#8243; el_class=&#8221;colonna_blu&#8221;][vc_column_text]Wakonda ha implementado un sistema de desarrollo que sigue los principios de la econom\u00eda circular, un sistema que hace que las tierras marginales ya no sean utilizables para la producci\u00f3n agr\u00edcola tradicional. Gracias a nuestras metodolog\u00edas es posible alcanzar rendimientos de hasta mil toneladas de producto fresco por hect\u00e1rea al a\u00f1o, con un coste por tonelada baj\u00edsimo. Esto supone una productividad hasta cuatro veces mayor que la del ma\u00edz y utiliza hasta 10 veces menos agua. En zonas semi\u00e1ridas el sistema Wakonda posibilita el desarrollo de la cr\u00eda de animales, tanto para la producci\u00f3n de carne como de leche.[\/vc_column_text][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_column_text]El proceso de transformaci\u00f3n de Ofi nos permite obtener productos alimenticios saludables y de alta calidad, as\u00ed como producir piensos animales ricos en prote\u00ednas aptos para una agricultura sostenible. Nuestra tecnolog\u00eda nos permite iniciar un sistema de fermentaci\u00f3n exclusivo que nos permite elevar el contenido de prote\u00edna del alimento producido hasta un 30% de la sustancia seca, creando las condiciones para reducir la dependencia de fertilizantes y alimentos for\u00e1neos y satisfacer la demanda cada vez mayor. para la carne y la leche disponibles en el mercado.[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_raw_html]JTNDc2NyaXB0JTIwc3JjJTNEJTIyaHR0cHMlM0ElMkYlMkZhamF4Lmdvb2dsZWFwaXMuY29tJTJGYWpheCUyRmxpYnMlMkZqcXVlcnklMkYzLjYuNCUyRmpxdWVyeS5taW4uanMlMjIlM0UlM0MlMkZzY3JpcHQlM0UlMEElM0NzY3JpcHQlMjB0eXBlJTNEJTIydGV4dCUyRmphdmFzY3JpcHQlMjIlM0UlMEElMEElMEElMjQlMjhkb2N1bWVudCUyOS5yZWFkeSUyOGZ1bmN0aW9uJTI4JTI5JTdCJTBBJTJGJTJGJTIwalF1ZXJ5JTI4ZG9jdW1lbnQlMjkucmVhZHklMjhmdW5jdGlvbiUyOCUyOSU3QiUwQSUwQSUwQSUyMCUyMCUyMCUyMCUyNCUyOCUyMi5pY29uLW5leHQlMjIlMjkuY2xpY2slMjhmdW5jdGlvbiUyOCUyOSU3QiUwQSUyMCUyMCUyMCUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMHZhbG9yZSUyMCUzRCUyMCUyNCUyOCUyMi52Y19jYXJvdXNlbC1zbGlkZWxpbmUtaW5uZXIlMjAlM0UlMjBkaXYlMjIlMjkuaW5kZXglMjglMjQlMjglMjIudmNfY2Fyb3VzZWwtc2xpZGVsaW5lLWlubmVyJTIwJTNFJTIwZGl2LnZjX2FjdGl2ZSUyMiUyOSUyOSUzQiUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMHZhbG9yZV9pbmNyJTIwJTNEJTIwdmFsb3JlJTIwJTJCJTIwMSUzQiUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMHZhciUyMGlkZW50aWYlMjAlM0QlMjAlMjglMjIlMjN0JTIyJTIwJTJCJTIwdmFsb3JlX2luY3IlMjklM0IlMEElMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMkYlMkYlMjBhbGVydCUyMCUyOGlkZW50aWYlMjklM0IlMEElMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMkYlMkYlMjBhbGVydCUyMCUyOHZhbG9yZSUyOSUzQiUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyNCUyOCUyMi5tYWRyZSUyMCUzRSUyMC52Y19jb2x1bW4taW5uZXIlMjAlM0UlMjAud3BiX3dyYXBwZXIlMjIlMjkuY2hpbGRyZW4lMjglMjkuaGlkZSUyOCUyOSUzQiUyMCUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyNCUyOGlkZW50aWYlMjkuc2hvdyUyOCUyOSUzQiUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMCUwQSUyRiUyRiUyMCUyMGFsZXJ0JTIwJTI4JTIyY2FpbyUyMiUyOSUzQiUwQSUwQSUyMCUyMCU3RCUyOSUzQiUyMCUwQSUwQSUyNCUyOCUyMi5pY29uLXByZXYlMjIlMjkuY2xpY2slMjhmdW5jdGlvbiUyOCUyOSU3QiUwQSUyMCUyMCUyMCUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMHZhbG9yZSUyMCUzRCUyMCUyNCUyOCUyMi52Y19jYXJvdXNlbC1zbGlkZWxpbmUtaW5uZXIlMjAlM0UlMjBkaXYlMjIlMjkuaW5kZXglMjglMjQlMjglMjIudmNfY2Fyb3VzZWwtc2xpZGVsaW5lLWlubmVyJTIwJTNFJTIwZGl2LnZjX2FjdGl2ZSUyMiUyOSUyOSUzQiUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyMCUyMHZhbG9yZV9pbmNyJTIwJTNEJTIwdmFsb3JlJTIwLTElM0IlMEElMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjB2YXIlMjBpZGVudGlmJTIwJTNEJTIwJTI4JTIyJTIzdCUyMiUyMCUyQiUyMHZhbG9yZV9pbmNyJTI5JTNCJTBBJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTJGJTJGYWxlcnQlMjAlMjhpZGVudGlmJTI5JTNCJTBBJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTIwJTJGJTJGJTIwYWxlcnQlMjAlMjh2YWxvcmUlMjklM0IlMEElMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjQlMjglMjIubWFkcmUlMjAlM0UlMjAudmNfY29sdW1uLWlubmVyJTIwJTNFJTIwLndwYl93cmFwcGVyJTIyJTI5LmNoaWxkcmVuJTI4JTI5LmhpZGUlMjglMjklM0IlMEElMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjQlMjhpZGVudGlmJTI5LnNob3clMjglMjklM0IlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMEElMkYlMkYlMjAlMjBhbGVydCUyMCUyOCUyMmNhaW8lMjIlMjklM0IlMEElMEElMjAlMjAlN0QlMjklM0IlMjAlMjAlMEElMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMEElMEElMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMkYlMkZhbGVydCUyMCUyOCUyMkNJQU8lMjIlMjklM0IlMEElMjAlMjAlMjAlMjAlN0QlMjklM0IlMEElMjAlMjAlMjAlMjAlM0MlMkZzY3JpcHQlM0U=[\/vc_raw_html][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; css=&#8221;.vc_custom_1670924541731{background-color: #a67446 !important;}&#8221; el_id=&#8221;agenda_row&#8221;][vc_column][vc_column_text] AGENDA 2030 La Agenda 2030 de Naciones Unidas persigue una lista de 17 objetivos. El sistema Wakonda contribuye al logro de 13 de ellos, con especial atenci\u00f3n a la producci\u00f3n de alimentos, la adaptaci\u00f3n al cambio clim\u00e1tico y la reducci\u00f3n de la pobreza.[\/vc_column_text][vc_row_inner][vc_column_inner][vc_images_carousel images=&#8221;1238,1239,1240,1242,1251,1253,1243,1244,1245,1246,1247,1252,1248&#8243; img_size=&#8221;full&#8221; onclick=&#8221;link_no&#8221; slides_per_view=&#8221;5&#8243; hide_pagination_control=&#8221;yes&#8221; partial_view=&#8221;yes&#8221;][\/vc_column_inner][\/vc_row_inner][vc_row_inner el_id=&#8221;elenco_obiettivi&#8221;][vc_column_inner el_class=&#8221;madre&#8221; width=&#8221;1\/2&#8243;][vc_column_text el_id=&#8221;t0&#8243;] Derrotar la probeza Tenemos la ambici\u00f3n de poner a disposici\u00f3n un sistema que permita el desarrollo de las zonas \u00e1ridas y semi\u00e1ridas del planeta, posibilitando el cultivo y la ganader\u00eda en zonas donde ahora no es posible, a un precio accesible, con el resultado de aumentar los ingresos. disponibles y reducir la pobreza relativa y absoluta. [\/vc_column_text][vc_column_text el_id=&#8221;t1&#8243;] Derrota el hambre Nuestra mayor ambici\u00f3n es alimentar el planeta y ayudar a vencer el hambre, y la Opuntia es perfecta para este objetivo, porque nos permite recuperar tierras menos f\u00e9rtiles y marginales y producir piensos para animales precisamente donde es m\u00e1s dif\u00edcil o imposible criar animales. [\/vc_column_text][vc_column_text el_id=&#8221;t2&#8243;] Salud y Bienestar Opuntia consigue regenerar suelos contaminados por metales pesados e hidrocarburos, que muchas veces generan graves problemas por la contaminaci\u00f3n de los acu\u00edferos. Desde Opuntia tambi\u00e9n es posible producir biofloculantes a bajo coste, para la depuraci\u00f3n de aguas residuales y su reutilizaci\u00f3n en el \u00e1mbito agr\u00edcola.[\/vc_column_text][vc_column_text el_id=&#8221;t3&#8243;] Igualidad de g\u00e9nero El &#8220;trabajo&#8221; es la principal herramienta para el &#8220;empoderamiento&#8221; femenino, para lograr realmente la igualdad de g\u00e9nero. La mayor\u00eda de las actividades de producci\u00f3n y procesamiento de Wakonda pueden ser gestionadas por mujeres, la mecanizaci\u00f3n de la plantaci\u00f3n y el procesamiento les permite trabajar sin necesidad de realizar un gran esfuerzo muscular. [\/vc_column_text][vc_column_text el_id=&#8221;t4&#8243;] Servicios de agua pura y saneamiento La gesti\u00f3n eficiente de los recursos h\u00eddricos es un punto distintivo del proyecto Wakonda, gracias al cual se puede obtener el triple de producci\u00f3n de ma\u00edz en una hect\u00e1rea de terreno, consumiendo 10 veces menos agua. El agua ahorrada o extra\u00edda de Ofi puede destinarse a otros usos, mejorando las condiciones de vida y\/o la producci\u00f3n agr\u00edcola. [\/vc_column_text][vc_column_text el_id=&#8221;t5&#8243;] Energia limpia y accesible Ofi es la planta ideal para obtener grandes cantidades de biog\u00e1s para cogeneraci\u00f3n el\u00e9ctrica o biometano de forma sostenible: es el cultivo que convive m\u00e1s eficazmente con los campos agrovoltaicos, en particular en terrenos marginales o improductivos para cultivos tradicionales. [\/vc_column_text][vc_column_text el_id=&#8221;t6&#8243;] Trabajo decente y crecimiento economico Wakonda es un sistema ideal para el desarrollo de las zonas \u00e1ridas y semi\u00e1ridas del planeta, es decir, las que sufren las consecuencias del cambio clim\u00e1tico. Es posible fomentar un crecimiento econ\u00f3mico generalizado, inclusivo y sostenible, el empleo pleno y productivo, el trabajo digno tanto para mujeres que hombres, en las zonas m\u00e1s deprimidas de la cuenca mediterr\u00e1nea y en el \u00c1frica subsahariana. [\/vc_column_text][vc_column_text el_id=&#8221;t7&#8243;] Negocios, innovacion e infraestructuras Wakonda es un modelo reproducible en m\u00faltiples pa\u00edses, en modo plug &amp; play, con un modelo de transferencia de tecnolog\u00eda destinado a fomentar el desarrollo incluso en zonas deprimidas o con bajo impacto humano, generando empleo y crecimiento sostenible en el mediano y largo plazo. [\/vc_column_text][vc_column_text el_id=&#8221;t8&#8243;] Reducir las desigualdades El crecimiento econ\u00f3mico que se puede lograr mediante la adopci\u00f3n de Wakonda es un presagio de un aumento del empleo y de una distribuci\u00f3n del ingreso que parte del sector primario, la agricultura, y por lo tanto, por definici\u00f3n, tiende a reducir las desigualdades y las desigualdades en el ingreso. [\/vc_column_text][vc_column_text el_id=&#8221;t9&#8243;] Ciudades y comuninades sostenibles Opuntia contribuye a la biorremediaci\u00f3n de terrenos, permite recuperar vastas \u00e1reas abandonadas, garantiza la biodiversidad gracias a su rusticidad y bajo o nulo aporte de agroqu\u00edmicos, previene la inestabilidad hidrogeol\u00f3gica y es una barrera natural contra incendios. [\/vc_column_text][vc_column_text el_id=&#8221;t10&#8243;] Consumo y produccion responsable Con el modelo Wakonda aplicado en grandes extensiones de terreno, es posible producir simult\u00e1neamente alimentos saludables, piensos para la cr\u00eda de animales, biometano y digestato s\u00f3lido y l\u00edquido: todo ello en terrenos marginales y con una baja huella h\u00eddrica, por lo tanto en un proceso que es sostenible desde el punto de vista medioambiental. [\/vc_column_text][vc_column_text el_id=&#8221;t11&#8243;] Lucha contra el cambio climatico El modelo Wakonda permite producir mejor piensos, alimentos y bioenerg\u00eda en la misma hect\u00e1rea de tierra, proporcionando una herramienta para adaptarse a los efectos locales del cambio clim\u00e1tico. [\/vc_column_text][vc_column_text el_id=&#8221;t12&#8243;] Vida en la tierra Wakonda contribui para proteger, restaurar e promover o uso sustent\u00e1vel do ecossistema terrestre, combatendo a desertifica\u00e7\u00e3o, travando a degrada\u00e7\u00e3o da terra e travando a perda de diversidade biol\u00f3gica. Isto pode ser feito com investimentos de m\u00e9dia\/baixa intensidade de capital em compara\u00e7\u00e3o com a\u00e7\u00f5es de longo prazo.[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/2&#8243;][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner width=&#8221;1\/2&#8243; el_id=&#8221;t12&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;1\/2&#8243;][\/vc_column_inner][\/vc_row_inner][vc_row_inner disable_element=&#8221;yes&#8221;][vc_column_inner][vc_images_carousel images=&#8221;1238,1239,1240,1242,1251,1253,1243,1244,1245,1246,1247,1252,1248,1249,1250,1290&#8243; img_size=&#8221;full&#8221; onclick=&#8221;link_no&#8221; slides_per_view=&#8221;5&#8243; hide_pagination_control=&#8221;yes&#8221; partial_view=&#8221;yes&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row]","og_url":"https:\/\/www.wakonda.eu\/es\/ambition-es\/","og_site_name":"Wakonda","article_modified_time":"2023-11-07T10:26:53+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.wakonda.eu\/es\/ambition-es\/","url":"https:\/\/www.wakonda.eu\/es\/ambition-es\/","name":"Ambition - Wakonda","isPartOf":{"@id":"https:\/\/www.wakonda.eu\/#website"},"datePublished":"2023-11-06T11:36:13+00:00","dateModified":"2023-11-07T10:26:53+00:00","breadcrumb":{"@id":"https:\/\/www.wakonda.eu\/es\/ambition-es\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.wakonda.eu\/es\/ambition-es\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.wakonda.eu\/es\/ambition-es\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.wakonda.eu\/es\/"},{"@type":"ListItem","position":2,"name":"Ambition"}]},{"@type":"WebSite","@id":"https:\/\/www.wakonda.eu\/#website","url":"https:\/\/www.wakonda.eu\/","name":"Wakonda","description":"","publisher":{"@id":"https:\/\/www.wakonda.eu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.wakonda.eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Organization","@id":"https:\/\/www.wakonda.eu\/#organization","name":"Wakonda","url":"https:\/\/www.wakonda.eu\/","logo":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/www.wakonda.eu\/#\/schema\/logo\/image\/","url":"https:\/\/www.wakonda.eu\/wp-content\/uploads\/sites\/39\/2023\/05\/cropped-logo_wakonda.png","contentUrl":"https:\/\/www.wakonda.eu\/wp-content\/uploads\/sites\/39\/2023\/05\/cropped-logo_wakonda.png","width":256,"height":57,"caption":"Wakonda"},"image":{"@id":"https:\/\/www.wakonda.eu\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.wakonda.eu\/es\/wp-json\/wp\/v2\/pages\/2855","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.wakonda.eu\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.wakonda.eu\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.wakonda.eu\/es\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/www.wakonda.eu\/es\/wp-json\/wp\/v2\/comments?post=2855"}],"version-history":[{"count":2,"href":"https:\/\/www.wakonda.eu\/es\/wp-json\/wp\/v2\/pages\/2855\/revisions"}],"predecessor-version":[{"id":3130,"href":"https:\/\/www.wakonda.eu\/es\/wp-json\/wp\/v2\/pages\/2855\/revisions\/3130"}],"wp:attachment":[{"href":"https:\/\/www.wakonda.eu\/es\/wp-json\/wp\/v2\/media?parent=2855"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}